{"id":121,"date":"2017-04-04T17:32:19","date_gmt":"2017-04-04T17:32:19","guid":{"rendered":"https:\/\/gawoolsey.onewhitedove.com\/woolseyblog\/?p=121"},"modified":"2017-11-20T22:03:21","modified_gmt":"2017-11-20T22:03:21","slug":"walnut-street-baptist-church-pastor-woolseys-update-letter-1957","status":"publish","type":"post","link":"https:\/\/gawoolsey.onewhitedove.com\/woolseyblog\/2017\/04\/04\/walnut-street-baptist-church-pastor-woolseys-update-letter-1957\/","title":{"rendered":"Walnut Street Baptist Church &#8211; Pastor Woolsey&#8217;s Update Letter 1957"},"content":{"rendered":"<figure id=\"attachment_189\" aria-describedby=\"caption-attachment-189\" style=\"width: 235px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/gawoolsey.onewhitedove.com\/woolseyblog\/wp-content\/uploads\/2017\/04\/WSBCLetter57-1.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"size-medium wp-image-189\" src=\"https:\/\/gawoolsey.onewhitedove.com\/woolseyblog\/wp-content\/uploads\/2017\/04\/WSBCLetter57-1-235x300.jpg\" alt=\"\" width=\"235\" height=\"300\" srcset=\"https:\/\/gawoolsey.onewhitedove.com\/woolseyblog\/wp-content\/uploads\/2017\/04\/WSBCLetter57-1-235x300.jpg 235w, https:\/\/gawoolsey.onewhitedove.com\/woolseyblog\/wp-content\/uploads\/2017\/04\/WSBCLetter57-1-768x981.jpg 768w, https:\/\/gawoolsey.onewhitedove.com\/woolseyblog\/wp-content\/uploads\/2017\/04\/WSBCLetter57-1-802x1024.jpg 802w\" sizes=\"(max-width: 235px) 100vw, 235px\" \/><\/a><figcaption id=\"caption-attachment-189\" class=\"wp-caption-text\">Pastor Woolsey&#8217;s Christmas Letter 1957<\/figcaption><\/figure>\n<p>This is a scan of an update letter for Walnut Street Baptist Church that was in my Grandmother&#8217;s scrapbook.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>This is a scan of an update letter for Walnut Street Baptist Church that was in my Grandmother&#8217;s scrapbook.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"image","meta":[],"categories":[97,48],"tags":[52,54,7,53,5,6],"_links":{"self":[{"href":"https:\/\/gawoolsey.onewhitedove.com\/woolseyblog\/wp-json\/wp\/v2\/posts\/121"}],"collection":[{"href":"https:\/\/gawoolsey.onewhitedove.com\/woolseyblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gawoolsey.onewhitedove.com\/woolseyblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gawoolsey.onewhitedove.com\/woolseyblog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gawoolsey.onewhitedove.com\/woolseyblog\/wp-json\/wp\/v2\/comments?post=121"}],"version-history":[{"count":4,"href":"https:\/\/gawoolsey.onewhitedove.com\/woolseyblog\/wp-json\/wp\/v2\/posts\/121\/revisions"}],"predecessor-version":[{"id":243,"href":"https:\/\/gawoolsey.onewhitedove.com\/woolseyblog\/wp-json\/wp\/v2\/posts\/121\/revisions\/243"}],"wp:attachment":[{"href":"https:\/\/gawoolsey.onewhitedove.com\/woolseyblog\/wp-json\/wp\/v2\/media?parent=121"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gawoolsey.onewhitedove.com\/woolseyblog\/wp-json\/wp\/v2\/categories?post=121"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gawoolsey.onewhitedove.com\/woolseyblog\/wp-json\/wp\/v2\/tags?post=121"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}