{"id":26,"count":1,"description":"","link":"https:\/\/gawoolsey.onewhitedove.com\/woolseyblog\/tag\/public-dancing\/","name":"public dancing","slug":"public-dancing","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/gawoolsey.onewhitedove.com\/woolseyblog\/wp-json\/wp\/v2\/tags\/26"}],"collection":[{"href":"https:\/\/gawoolsey.onewhitedove.com\/woolseyblog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/gawoolsey.onewhitedove.com\/woolseyblog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/gawoolsey.onewhitedove.com\/woolseyblog\/wp-json\/wp\/v2\/posts?tags=26"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}